{"id":115,"date":"2024-04-04T12:59:27","date_gmt":"2024-04-04T12:59:27","guid":{"rendered":"https:\/\/www.manantialradio.cl\/web\/?p=115"},"modified":"2024-04-04T12:59:27","modified_gmt":"2024-04-04T12:59:27","slug":"hombre-murio-baleado-en-plena-via-publica-de-lo-prado-habria-sufrido-un-asalto","status":"publish","type":"post","link":"https:\/\/www.manantialradio.cl\/web\/2024\/04\/04\/hombre-murio-baleado-en-plena-via-publica-de-lo-prado-habria-sufrido-un-asalto\/","title":{"rendered":"Hombre muri\u00f3 baleado en plena v\u00eda p\u00fablica de Lo Prado: Habr\u00eda sufrido un asalto"},"content":{"rendered":"\n<p>La Polic\u00eda de Investigaciones (PDI) se encuentra investigando un<strong>&nbsp;homicidio que ocurri\u00f3 en la comuna de Lo Prado<\/strong>,&nbsp;<a href=\"https:\/\/www.radioagricultura.cl\/nacional\/2024\/02\/24\/vehiculo-incendiado-en-tunel-lo-prado-obligo-a-cortar-el-transito-en-la-ruta-68\/\">Regi\u00f3n Metropolitana<\/a>, durante la madrugada de este jueves.<\/p>\n\n\n\n<p>El asesinato sucedi\u00f3 en la intersecci\u00f3n de las calles&nbsp;<strong>San Pablo con Gabriela Mistral<\/strong>, a las afueras de un local nocturno, donde la v\u00edctima fatal -un chileno, mayor de edad- habr\u00eda puesto resistencia a un asalto.<\/p>\n\n\n\n<p>\u201c<strong>Fue agredido con un arma de fuego<\/strong>&nbsp;a las afueras de un local nocturno, el cual result\u00f3 lesionado de gravedad, fue trasladado hasta la&nbsp;<strong>Cl\u00ednica D\u00e1vila<\/strong>,&nbsp;<strong>donde se constat\u00f3 su deceso<\/strong>\u201c, se\u00f1al\u00f3 el comisario Ariel Alarc\u00f3n, de la Brigada de Homicidios Centro Norte de la PDI.<\/p>\n\n\n\n<p>Tambi\u00e9n coment\u00f3 que los primeros antecedentes indican que la v\u00edctima&nbsp;<strong>\u201chabr\u00eda sido asaltada para quitarle ciertas pertenencias\u201d<\/strong>&nbsp;y \u201cal resistirse fue agredida con arma de fuego, con diversos impactos bal\u00edsticos\u201d.<\/p>\n\n\n\n<p>Personal de Carabineros lleg\u00f3 hasta el sitio del suceso tras recibir una denuncia sobre una persona baleada, pero no encontraron ning\u00fan cuerpo. Sin embargo,&nbsp;<strong>s\u00ed la existencia de evidencia bal\u00edstica.<\/strong><\/p>\n\n\n\n<p>\u201cUna vez que agredida<strong>&nbsp;la v\u00edctima es traslada por transe\u00fantes y amigos de esta al centro asistencial&nbsp;<\/strong>que ya mencione. No habr\u00eda estado solo, pero se encontraba a las afueras del centro nocturno\u201d, indic\u00f3 el funcionario de la polic\u00eda civil.<\/p>\n\n\n\n<p>\u201cLos antecedentes preliminares que la persona fallecida era un asiduo participante de estas fiestas\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>La Brigada de Homicidios de la PDI qued\u00f3 a cargo de las diligencias con la finalidad de esclarecer los hechos. \u201cComo hay&nbsp;<strong>evidencia bal\u00edstica<\/strong>&nbsp;en ambos costados de la v\u00eda, vamos a tratar de dilucidar que es lo que finalmente pas\u00f3\u201d, coment\u00f3 el comisario Alarc\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Polic\u00eda de Investigaciones (PDI) se encuentra investigando un&nbsp;homicidio que ocurri\u00f3 en la comuna de Lo Prado,&nbsp;Regi\u00f3n Metropolitana, durante la madrugada de este jueves. El asesinato sucedi\u00f3 en la intersecci\u00f3n de las calles&nbsp;San Pablo con Gabriela Mistral, a las afueras&#8230;<\/p>\n","protected":false},"author":1,"featured_media":117,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/posts\/115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/comments?post=115"}],"version-history":[{"count":1,"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/posts\/115\/revisions"}],"predecessor-version":[{"id":118,"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/posts\/115\/revisions\/118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/media\/117"}],"wp:attachment":[{"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/media?parent=115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/categories?post=115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/tags?post=115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}