{"id":1329,"date":"2024-09-04T15:21:06","date_gmt":"2024-09-04T15:21:06","guid":{"rendered":"https:\/\/www.manantialradio.cl\/web\/?p=1329"},"modified":"2024-09-04T15:21:06","modified_gmt":"2024-09-04T15:21:06","slug":"cae-banda-que-hacia-turbazos-en-la-rm-entraban-a-robar-a-casas-en-la-madrugada-y-golpeaban-a-sus-residentes","status":"publish","type":"post","link":"https:\/\/www.manantialradio.cl\/web\/2024\/09\/04\/cae-banda-que-hacia-turbazos-en-la-rm-entraban-a-robar-a-casas-en-la-madrugada-y-golpeaban-a-sus-residentes\/","title":{"rendered":"Cae banda que hac\u00eda turbazos en la RM: Entraban a robar a casas en la madrugada y golpeaban a sus residentes"},"content":{"rendered":"\n<p>La Polic\u00eda de Investigaciones (PDI) y la Fiscal\u00eda Metropolitana Occidente lograron\u00a0<strong>desarticular una peligrosa banda delictual<\/strong>\u00a0dedicada a realizar<strong>\u00a0turbazos<\/strong>\u00a0<strong>en casas<\/strong>\u00a0de distintas comunas de la\u00a0<a href=\"https:\/\/www.meganoticias.cl\/temas\/region-metropolitana\/\" target=\"_blank\" rel=\"noreferrer noopener\">Regi\u00f3n Metropolitana<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">V\u00edctimas eran intimidadas con armas de fuego&nbsp;<\/h2>\n\n\n\n<p>Seg\u00fan explic\u00f3 el&nbsp;<strong>prefecto Marco Ram\u00edrez<\/strong>,<strong>&nbsp;<\/strong>jefe nacional de Robos y Focos Criminales, los robos tuvieron lugar en domicilios de&nbsp;<strong>Maip\u00fa, Pudahuel y Quinta Normal<\/strong>.&nbsp;\u00abIrrump\u00edan en horas de la madrugada,&nbsp;<strong>con armas de fuego, encapuchados<\/strong>, y sustra\u00edan variadas especies desde el interior de las casas,&nbsp;<strong>golpeando a los residentes<\/strong>\u00ab, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>\u00abEstos delincuentes usaban la<strong>&nbsp;modalidad del &#8216;turbazo&#8217;<\/strong>&nbsp;e<strong>&nbsp;<\/strong>ingresaban en manada para sustraer elementos\u00bb, inform\u00f3 la autoridad. Las v\u00edctimas eran<strong>&nbsp;adultos mayores, j\u00f3venes y ni\u00f1os<\/strong>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Detectives de la Brigada Investigadora de Robos (Biro) Occidente lograron la detenci\u00f3n de sus miembros tras concretar<strong>&nbsp;16 \u00f3rdenes de entrada y registro<\/strong>.&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L\u00edder de la banda ya hab\u00eda sido detenido&nbsp;<\/h2>\n\n\n\n<p>El<strong>&nbsp;fiscal Marcos Past\u00e9n<\/strong>&nbsp;explic\u00f3 que el pasado&nbsp;<strong>26 de julio y 8 de agosto&nbsp;<\/strong>se cometieron turbazos en la capital. En la primera fecha \u00abtuvimos, en la madrugada, tres delitos en Pudahuel, Quinta Normal y Maip\u00fa\u00bb.&nbsp;<\/p>\n\n\n\n<p>\u00abA ra\u00edz de este fen\u00f3meno que fue ampliamente difundido, como Fiscal\u00eda decidimos crear una fuerza de tarea (&#8230;) En un mes, podemos dar cuenta de la<strong>&nbsp;detenci\u00f3n de 10 personas<\/strong>&nbsp;vinculadas a estos hechos\u00bb, coment\u00f3.<\/p>\n\n\n\n<p>Seg\u00fan se\u00f1al\u00f3 el persecutor, siete de los arrestados<strong>&nbsp;contaban con \u00f3rdenes de detenci\u00f3n<\/strong>&nbsp;vigente por estos mismos hechos, \u00abporque hab\u00edamos logrado situarlos en los sitios del suceso\u00bb. Los otros tres, en tanto, fueron detenidos en flagrancia.<\/p>\n\n\n\n<p>\u00abAdem\u00e1s, pasa a control de detenci\u00f3n una persona que estaba al interior de un recinto penitenciario que&nbsp;<strong>hab\u00eda sido detenida en estos d\u00edas<\/strong>&nbsp;por receptaci\u00f3n y que, a nuestro juicio,&nbsp;<strong>era quien lideraba esta banda<\/strong>\u00ab, a\u00f1adi\u00f3 el fiscal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Polic\u00eda de Investigaciones (PDI) y la Fiscal\u00eda Metropolitana Occidente lograron\u00a0desarticular una peligrosa banda delictual\u00a0dedicada a realizar\u00a0turbazos\u00a0en casas\u00a0de distintas comunas de la\u00a0Regi\u00f3n Metropolitana. V\u00edctimas eran intimidadas con armas de fuego&nbsp; Seg\u00fan explic\u00f3 el&nbsp;prefecto Marco Ram\u00edrez,&nbsp;jefe nacional de Robos y Focos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1330,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/posts\/1329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/comments?post=1329"}],"version-history":[{"count":1,"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/posts\/1329\/revisions"}],"predecessor-version":[{"id":1331,"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/posts\/1329\/revisions\/1331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/media\/1330"}],"wp:attachment":[{"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/media?parent=1329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/categories?post=1329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manantialradio.cl\/web\/wp-json\/wp\/v2\/tags?post=1329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}